{"id":3296,"date":"2016-10-27T15:13:09","date_gmt":"2016-10-27T13:13:09","guid":{"rendered":"\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg"},"modified":"2016-10-27T15:13:09","modified_gmt":"2016-10-27T13:13:09","slug":"olivetti-cat-flange-sett2015-web_pagina_065","status":"inherit","type":"attachment","link":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/","title":{"rendered":"olivetti-cat-flange-sett2015-web_pagina_065"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3296","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>olivetti-cat-flange-sett2015-web_pagina_065 - Olivetti Flange<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"olivetti-cat-flange-sett2015-web_pagina_065 - Olivetti Flange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/\" \/>\n<meta property=\"og:site_name\" content=\"Olivetti Flange\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-ansi-300lb\\\/olivetti-cat-flange-sett2015-web_pagina_065\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-ansi-300lb\\\/olivetti-cat-flange-sett2015-web_pagina_065\\\/\",\"name\":\"olivetti-cat-flange-sett2015-web_pagina_065 - Olivetti Flange\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\"},\"datePublished\":\"2016-10-27T13:13:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-ansi-300lb\\\/olivetti-cat-flange-sett2015-web_pagina_065\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-ansi-300lb\\\/olivetti-cat-flange-sett2015-web_pagina_065\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-ansi-300lb\\\/olivetti-cat-flange-sett2015-web_pagina_065\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flange\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FLANGE ANSI 300lb (SLIP ON WELDING)\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-ansi-300lb\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"olivetti-cat-flange-sett2015-web_pagina_065\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"name\":\"Olivetti Flange\",\"description\":\"Fabbrica Italiana Flange\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\",\"name\":\"Olivetti Flange\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"width\":545,\"height\":74,\"caption\":\"Olivetti Flange\"},\"image\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"olivetti-cat-flange-sett2015-web_pagina_065 - Olivetti Flange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/","og_locale":"it_IT","og_type":"article","og_title":"olivetti-cat-flange-sett2015-web_pagina_065 - Olivetti Flange","og_url":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/","og_site_name":"Olivetti Flange","og_image":[{"width":1000,"height":1414,"url":"http:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/","url":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/","name":"olivetti-cat-flange-sett2015-web_pagina_065 - Olivetti Flange","isPartOf":{"@id":"http:\/\/www.olivettiflange.com\/it\/#website"},"datePublished":"2016-10-27T13:13:09+00:00","breadcrumb":{"@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/olivetti-cat-flange-sett2015-web_pagina_065\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.olivettiflange.com\/it\/"},{"@type":"ListItem","position":2,"name":"Flange","item":"http:\/\/www.olivettiflange.com\/it\/flange\/"},{"@type":"ListItem","position":3,"name":"FLANGE ANSI 300lb (SLIP ON WELDING)","item":"http:\/\/www.olivettiflange.com\/it\/flange\/flange-ansi-300lb\/"},{"@type":"ListItem","position":4,"name":"olivetti-cat-flange-sett2015-web_pagina_065"}]},{"@type":"WebSite","@id":"http:\/\/www.olivettiflange.com\/it\/#website","url":"http:\/\/www.olivettiflange.com\/it\/","name":"Olivetti Flange","description":"Fabbrica Italiana Flange","publisher":{"@id":"http:\/\/www.olivettiflange.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.olivettiflange.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.olivettiflange.com\/it\/#organization","name":"Olivetti Flange","url":"http:\/\/www.olivettiflange.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","contentUrl":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","width":545,"height":74,"caption":"Olivetti Flange"},"image":{"@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-212x300.jpg 212w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-768x1086.jpg 768w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-724x1024.jpg 724w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-658x930.jpg 658w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg 1000w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":1414,"file":"2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg","sizes":{"thumbnail":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-150x150.jpg"},"medium":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-212x300.jpg","width":212,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-212x300.jpg"},"medium_large":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-768x1086.jpg","width":768,"height":1086,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-768x1086.jpg"},"large":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-724x1024.jpg","width":724,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-724x1024.jpg"},"widget":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-36x36.jpg","width":36,"height":36,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-36x36.jpg"},"slider_thumb":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-70x50.jpg","width":70,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-70x50.jpg"},"fullsize":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-658x930.jpg","width":658,"height":930,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-658x930.jpg"},"testimonial-thumb":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-120x140.jpg","width":120,"height":140,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-120x140.jpg"},"slide_thumb":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-90x45.jpg","width":90,"height":45,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-90x45.jpg"},"staff-thumb":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-220x195.jpg","width":220,"height":195,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-220x195.jpg"},"recent_sc_portfolio":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-60x60.jpg","width":60,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-60x60.jpg"},"port3":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-514x368.jpg","width":514,"height":368,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-514x368.jpg"},"port3_list":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-165x254.jpg","width":165,"height":254,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-165x254.jpg"},"port2":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-460x275.jpg","width":460,"height":275,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-460x275.jpg"},"port2_list":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-259x194.jpg","width":259,"height":194,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-259x194.jpg"},"port4":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-514x360.jpg","width":514,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-514x360.jpg"},"port4_list":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-120x340.jpg","width":120,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-120x340.jpg"},"port1_list":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-540x387.jpg","width":540,"height":387,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-540x387.jpg"},"seven_tw_mason":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-632x350.jpg","width":632,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-632x350.jpg"},"one_fourth_mason":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-257x240.jpg","width":257,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-257x240.jpg"},"one_fourth_al_mason":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-257x350.jpg","width":257,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-257x350.jpg"},"one_third_mason":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-351x350.jpg","width":351,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-351x350.jpg"},"five_tw_mason":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-445x354.jpg","width":445,"height":354,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-445x354.jpg"},"five_tw_al_mason":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-445x140.jpg","width":445,"height":140,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-445x140.jpg"},"vertical":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-292x170.jpg","width":292,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-292x170.jpg"},"post_author":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-75x75.jpg"},"featured_blog":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-520x380.jpg","width":520,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-520x380.jpg"},"blog":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-825x340.jpg","width":825,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-825x340.jpg"},"blog_categories":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-140x82.jpg","width":140,"height":82,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-140x82.jpg"},"blog_recent":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-88x88.jpg","width":88,"height":88,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-88x88.jpg"},"great_gallery":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-600x600.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-600x600.jpg"},"post_thumbnail":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-40x40.jpg","width":40,"height":40,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-40x40.jpg"},"services_media":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-516x284.jpg","width":516,"height":284,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-516x284.jpg"},"portfolio_bottom":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-1000x400.jpg","width":1000,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-1000x400.jpg"},"portfolio_side":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-819x840.jpg","width":819,"height":840,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-819x840.jpg"},"swiper_slider":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-450x500.jpg","width":450,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-450x500.jpg"},"sow-carousel-default":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065-272x182.jpg"},"full":{"file":"Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg","width":1000,"height":1414,"mime_type":"image\/jpeg","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3294,"source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_065.jpg","_links":{"self":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/media\/3296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/comments?post=3296"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":3294,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/3294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}