{"id":3578,"date":"2018-02-28T18:23:49","date_gmt":"2018-02-28T17:23:49","guid":{"rendered":"http:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018.gif"},"modified":"2018-02-28T18:24:00","modified_gmt":"2018-02-28T17:24:00","slug":"ifat2018","status":"inherit","type":"attachment","link":"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/","title":{"rendered":"IFAT-2018"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3578","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IFAT-2018 - Olivetti Flange<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IFAT-2018 - Olivetti Flange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Olivetti Flange\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-28T17:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"468\" \/>\n\t<meta property=\"og:image:height\" content=\"60\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/ifat-2018\\\/ifat2018\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/ifat-2018\\\/ifat2018\\\/\",\"name\":\"IFAT-2018 - Olivetti Flange\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\"},\"datePublished\":\"2018-02-28T17:23:49+00:00\",\"dateModified\":\"2018-02-28T17:24:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/ifat-2018\\\/ifat2018\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/ifat-2018\\\/ifat2018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/ifat-2018\\\/ifat2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IFAT 2018\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/ifat-2018\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IFAT-2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"name\":\"Olivetti Flange\",\"description\":\"Fabbrica Italiana Flange\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\",\"name\":\"Olivetti Flange\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"width\":545,\"height\":74,\"caption\":\"Olivetti Flange\"},\"image\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IFAT-2018 - Olivetti Flange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/","og_locale":"it_IT","og_type":"article","og_title":"IFAT-2018 - Olivetti Flange","og_url":"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/","og_site_name":"Olivetti Flange","article_modified_time":"2018-02-28T17:24:00+00:00","og_image":[{"width":468,"height":60,"url":"http:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/","url":"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/","name":"IFAT-2018 - Olivetti Flange","isPartOf":{"@id":"http:\/\/www.olivettiflange.com\/it\/#website"},"datePublished":"2018-02-28T17:23:49+00:00","dateModified":"2018-02-28T17:24:00+00:00","breadcrumb":{"@id":"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.olivettiflange.com\/it\/ifat-2018\/ifat2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.olivettiflange.com\/it\/"},{"@type":"ListItem","position":2,"name":"IFAT 2018","item":"http:\/\/www.olivettiflange.com\/it\/ifat-2018\/"},{"@type":"ListItem","position":3,"name":"IFAT-2018"}]},{"@type":"WebSite","@id":"http:\/\/www.olivettiflange.com\/it\/#website","url":"http:\/\/www.olivettiflange.com\/it\/","name":"Olivetti Flange","description":"Fabbrica Italiana Flange","publisher":{"@id":"http:\/\/www.olivettiflange.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.olivettiflange.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.olivettiflange.com\/it\/#organization","name":"Olivetti Flange","url":"http:\/\/www.olivettiflange.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","contentUrl":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","width":545,"height":74,"caption":"Olivetti Flange"},"image":{"@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018.gif'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"38\" src=\"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-300x38.gif\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-300x38.gif 300w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-460x60.gif 460w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/gif","media_details":{"width":468,"height":60,"file":"2018\/02\/IFAT2018.gif","sizes":{"thumbnail":{"file":"IFAT2018-150x60.gif","width":150,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-150x60.gif"},"medium":{"file":"IFAT2018-300x38.gif","width":300,"height":38,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-300x38.gif"},"widget":{"file":"IFAT2018-36x36.gif","width":36,"height":36,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-36x36.gif"},"slider_thumb":{"file":"IFAT2018-70x50.gif","width":70,"height":50,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-70x50.gif"},"testimonial-thumb":{"file":"IFAT2018-120x60.gif","width":120,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-120x60.gif"},"slide_thumb":{"file":"IFAT2018-90x45.gif","width":90,"height":45,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-90x45.gif"},"staff-thumb":{"file":"IFAT2018-220x60.gif","width":220,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-220x60.gif"},"recent_sc_portfolio":{"file":"IFAT2018-60x60.gif","width":60,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-60x60.gif"},"port3_list":{"file":"IFAT2018-165x60.gif","width":165,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-165x60.gif"},"port2":{"file":"IFAT2018-460x60.gif","width":460,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-460x60.gif"},"port2_list":{"file":"IFAT2018-259x60.gif","width":259,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-259x60.gif"},"port4_list":{"file":"IFAT2018-120x60.gif","width":120,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-120x60.gif"},"one_fourth_mason":{"file":"IFAT2018-257x60.gif","width":257,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-257x60.gif"},"one_fourth_al_mason":{"file":"IFAT2018-257x60.gif","width":257,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-257x60.gif"},"one_third_mason":{"file":"IFAT2018-351x60.gif","width":351,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-351x60.gif"},"five_tw_mason":{"file":"IFAT2018-445x60.gif","width":445,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-445x60.gif"},"five_tw_al_mason":{"file":"IFAT2018-445x60.gif","width":445,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-445x60.gif"},"vertical":{"file":"IFAT2018-292x60.gif","width":292,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-292x60.gif"},"post_author":{"file":"IFAT2018-75x60.gif","width":75,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-75x60.gif"},"blog_categories":{"file":"IFAT2018-140x60.gif","width":140,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-140x60.gif"},"blog_recent":{"file":"IFAT2018-88x60.gif","width":88,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-88x60.gif"},"post_thumbnail":{"file":"IFAT2018-40x40.gif","width":40,"height":40,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-40x40.gif"},"swiper_slider":{"file":"IFAT2018-450x60.gif","width":450,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-450x60.gif"},"sow-carousel-default":{"file":"IFAT2018-272x60.gif","width":272,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018-272x60.gif"},"full":{"file":"IFAT2018.gif","width":468,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018.gif"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3575,"source_url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2018\/02\/IFAT2018.gif","_links":{"self":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/media\/3578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/comments?post=3578"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3575,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/posts\/3575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}