{"id":3148,"date":"2016-10-27T10:27:15","date_gmt":"2016-10-27T08:27:15","guid":{"rendered":"\/it\/?page_id=3148"},"modified":"2016-12-16T14:51:16","modified_gmt":"2016-12-16T13:51:16","slug":"flange-libere-per-cartella-pn-16","status":"publish","type":"page","link":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/","title":{"rendered":"FLANGE LIBERE PER CARTELLA PN 16"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3150\" src=\"\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_081-212x300.jpg\" sizes=\"(max-width: 1000px) 100vw, 1000px\" srcset=\"\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_081-212x300.jpg 212w, \/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_081-768x1086.jpg 768w, \/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_081-724x1024.jpg 724w, \/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_081-658x930.jpg 658w, \/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_081.jpg 1000w\" alt=\"olivetti-cat-flange-sett2015-web_pagina_081\" width=\"1000\" height=\"1414\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2983,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3148","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FLANGE LIBERE PER CARTELLA PN 16 - Olivetti Flange<\/title>\n<meta name=\"description\" content=\"Flange metalliche per tubazioni LIBERE PER CARTELLA PN 16. Flange LIBERE PER CARTELLA PN 16. Olivetti Fabbrica Italiana Flange\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FLANGE LIBERE PER CARTELLA PN 16 - Olivetti Flange\" \/>\n<meta property=\"og:description\" content=\"Flange metalliche per tubazioni LIBERE PER CARTELLA PN 16. Flange LIBERE PER CARTELLA PN 16. Olivetti Fabbrica Italiana Flange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Olivetti Flange\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-16T13:51:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-libere-per-cartella-pn-16\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-libere-per-cartella-pn-16\\\/\",\"name\":\"FLANGE LIBERE PER CARTELLA PN 16 - Olivetti Flange\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\"},\"datePublished\":\"2016-10-27T08:27:15+00:00\",\"dateModified\":\"2016-12-16T13:51:16+00:00\",\"description\":\"Flange metalliche per tubazioni LIBERE PER CARTELLA PN 16. Flange LIBERE PER CARTELLA PN 16. Olivetti Fabbrica Italiana Flange\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-libere-per-cartella-pn-16\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-libere-per-cartella-pn-16\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-libere-per-cartella-pn-16\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flange\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FLANGE LIBERE PER CARTELLA PN 16\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"name\":\"Olivetti Flange\",\"description\":\"Fabbrica Italiana Flange\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\",\"name\":\"Olivetti Flange\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"width\":545,\"height\":74,\"caption\":\"Olivetti Flange\"},\"image\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FLANGE LIBERE PER CARTELLA PN 16 - Olivetti Flange","description":"Flange metalliche per tubazioni LIBERE PER CARTELLA PN 16. Flange LIBERE PER CARTELLA PN 16. Olivetti Fabbrica Italiana Flange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/","og_locale":"it_IT","og_type":"article","og_title":"FLANGE LIBERE PER CARTELLA PN 16 - Olivetti Flange","og_description":"Flange metalliche per tubazioni LIBERE PER CARTELLA PN 16. Flange LIBERE PER CARTELLA PN 16. Olivetti Fabbrica Italiana Flange","og_url":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/","og_site_name":"Olivetti Flange","article_modified_time":"2016-12-16T13:51:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/","url":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/","name":"FLANGE LIBERE PER CARTELLA PN 16 - Olivetti Flange","isPartOf":{"@id":"http:\/\/www.olivettiflange.com\/it\/#website"},"datePublished":"2016-10-27T08:27:15+00:00","dateModified":"2016-12-16T13:51:16+00:00","description":"Flange metalliche per tubazioni LIBERE PER CARTELLA PN 16. Flange LIBERE PER CARTELLA PN 16. Olivetti Fabbrica Italiana Flange","breadcrumb":{"@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-libere-per-cartella-pn-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.olivettiflange.com\/it\/"},{"@type":"ListItem","position":2,"name":"Flange","item":"http:\/\/www.olivettiflange.com\/it\/flange\/"},{"@type":"ListItem","position":3,"name":"FLANGE LIBERE PER CARTELLA PN 16"}]},{"@type":"WebSite","@id":"http:\/\/www.olivettiflange.com\/it\/#website","url":"http:\/\/www.olivettiflange.com\/it\/","name":"Olivetti Flange","description":"Fabbrica Italiana Flange","publisher":{"@id":"http:\/\/www.olivettiflange.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.olivettiflange.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.olivettiflange.com\/it\/#organization","name":"Olivetti Flange","url":"http:\/\/www.olivettiflange.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","contentUrl":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","width":545,"height":74,"caption":"Olivetti Flange"},"image":{"@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/3148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/comments?post=3148"}],"version-history":[{"count":3,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/3148\/revisions"}],"predecessor-version":[{"id":3462,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/3148\/revisions\/3462"}],"up":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/2983"}],"wp:attachment":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/media?parent=3148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}