{"id":3228,"date":"2016-10-27T12:06:36","date_gmt":"2016-10-27T10:06:36","guid":{"rendered":"\/it\/?page_id=3228"},"modified":"2016-11-10T10:21:41","modified_gmt":"2016-11-10T09:21:41","slug":"flange-a-collare-da-saldare-di-testa-pn-25","status":"publish","type":"page","link":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/","title":{"rendered":"FLANGE A COLLARE DA SALDARE DI TESTA PN 25"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3230\" src=\"\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_038-211x300.jpg\" sizes=\"(max-width: 1000px) 100vw, 1000px\" srcset=\"\/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_038-211x300.jpg 211w, \/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_038-768x1091.jpg 768w, \/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_038-721x1024.jpg 721w, \/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_038-654x930.jpg 654w, \/wp-content\/uploads\/2016\/10\/Olivetti-cat.-FLANGE-sett2015-web_Pagina_038.jpg 1000w\" alt=\"olivetti-cat-flange-sett2015-web_pagina_038\" width=\"1000\" height=\"1421\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2983,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3228","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FLANGE A COLLARE DA SALDARE DI TESTA PN 25 - Olivetti Flange<\/title>\n<meta name=\"description\" content=\"Questo tipo di flangia (collare) \u00e8 destinato ad un accoppiamento da saldatura di testa PN 25. FLANGE A COLLARE DA SALDARE DI TESTA PN 25. Olivetti Flange\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FLANGE A COLLARE DA SALDARE DI TESTA PN 25 - Olivetti Flange\" \/>\n<meta property=\"og:description\" content=\"Questo tipo di flangia (collare) \u00e8 destinato ad un accoppiamento da saldatura di testa PN 25. FLANGE A COLLARE DA SALDARE DI TESTA PN 25. Olivetti Flange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/\" \/>\n<meta property=\"og:site_name\" content=\"Olivetti Flange\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-10T09:21:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-a-collare-da-saldare-di-testa-pn-25\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-a-collare-da-saldare-di-testa-pn-25\\\/\",\"name\":\"FLANGE A COLLARE DA SALDARE DI TESTA PN 25 - Olivetti Flange\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\"},\"datePublished\":\"2016-10-27T10:06:36+00:00\",\"dateModified\":\"2016-11-10T09:21:41+00:00\",\"description\":\"Questo tipo di flangia (collare) \u00e8 destinato ad un accoppiamento da saldatura di testa PN 25. FLANGE A COLLARE DA SALDARE DI TESTA PN 25. Olivetti Flange\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-a-collare-da-saldare-di-testa-pn-25\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-a-collare-da-saldare-di-testa-pn-25\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/flange-a-collare-da-saldare-di-testa-pn-25\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flange\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/flange\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FLANGE A COLLARE DA SALDARE DI TESTA PN 25\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"name\":\"Olivetti Flange\",\"description\":\"Fabbrica Italiana Flange\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\",\"name\":\"Olivetti Flange\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"width\":545,\"height\":74,\"caption\":\"Olivetti Flange\"},\"image\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FLANGE A COLLARE DA SALDARE DI TESTA PN 25 - Olivetti Flange","description":"Questo tipo di flangia (collare) \u00e8 destinato ad un accoppiamento da saldatura di testa PN 25. FLANGE A COLLARE DA SALDARE DI TESTA PN 25. Olivetti Flange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/","og_locale":"it_IT","og_type":"article","og_title":"FLANGE A COLLARE DA SALDARE DI TESTA PN 25 - Olivetti Flange","og_description":"Questo tipo di flangia (collare) \u00e8 destinato ad un accoppiamento da saldatura di testa PN 25. FLANGE A COLLARE DA SALDARE DI TESTA PN 25. Olivetti Flange","og_url":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/","og_site_name":"Olivetti Flange","article_modified_time":"2016-11-10T09:21:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/","url":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/","name":"FLANGE A COLLARE DA SALDARE DI TESTA PN 25 - Olivetti Flange","isPartOf":{"@id":"http:\/\/www.olivettiflange.com\/it\/#website"},"datePublished":"2016-10-27T10:06:36+00:00","dateModified":"2016-11-10T09:21:41+00:00","description":"Questo tipo di flangia (collare) \u00e8 destinato ad un accoppiamento da saldatura di testa PN 25. FLANGE A COLLARE DA SALDARE DI TESTA PN 25. Olivetti Flange","breadcrumb":{"@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.olivettiflange.com\/it\/flange\/flange-a-collare-da-saldare-di-testa-pn-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.olivettiflange.com\/it\/"},{"@type":"ListItem","position":2,"name":"Flange","item":"http:\/\/www.olivettiflange.com\/it\/flange\/"},{"@type":"ListItem","position":3,"name":"FLANGE A COLLARE DA SALDARE DI TESTA PN 25"}]},{"@type":"WebSite","@id":"http:\/\/www.olivettiflange.com\/it\/#website","url":"http:\/\/www.olivettiflange.com\/it\/","name":"Olivetti Flange","description":"Fabbrica Italiana Flange","publisher":{"@id":"http:\/\/www.olivettiflange.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.olivettiflange.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.olivettiflange.com\/it\/#organization","name":"Olivetti Flange","url":"http:\/\/www.olivettiflange.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","contentUrl":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","width":545,"height":74,"caption":"Olivetti Flange"},"image":{"@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/3228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/comments?post=3228"}],"version-history":[{"count":3,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/3228\/revisions"}],"predecessor-version":[{"id":3430,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/3228\/revisions\/3430"}],"up":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/pages\/2983"}],"wp:attachment":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/media?parent=3228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}