{"id":2658,"date":"2016-10-25T22:58:05","date_gmt":"2016-10-25T20:58:05","guid":{"rendered":"\/it\/?p=2658"},"modified":"2016-12-15T16:01:59","modified_gmt":"2016-12-15T15:01:59","slug":"siamo-presenti-eima-international-2016","status":"publish","type":"post","link":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/","title":{"rendered":"Siamo presenti a EIMA International 2016"},"content":{"rendered":"<p>Siamo presenti a EIMA International 2016 presso il:<br \/>\nPADIGLIONE 21 &#8211; STAND B24<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2659\" src=\"\/wp-content\/uploads\/2016\/10\/EIMA2016.jpg\" alt=\"Microsoft Word - EIMA.docx\" width=\"395\" height=\"384\" srcset=\"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016.jpg 937w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016-300x292.jpg 300w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016-768x748.jpg 768w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016-36x36.jpg 36w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016-930x905.jpg 930w, https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016-40x40.jpg 40w\" sizes=\"(max-width: 395px) 100vw, 395px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo presenti a EIMA International 2016 presso il: PADIGLIONE 21 &#8211; STAND B24<\/p>\n","protected":false},"author":1,"featured_media":2659,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-2658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Siamo presenti a EIMA International 2016 - Olivetti Flange<\/title>\n<meta name=\"description\" content=\"Siamo presenti a EIMA International 2016 a Bologna dal 9 al 13 novembre 2016 presso il: PADIGLIONE 21 - STAND B24. Olivetti Flange\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siamo presenti a EIMA International 2016 - Olivetti Flange\" \/>\n<meta property=\"og:description\" content=\"Siamo presenti a EIMA International 2016 a Bologna dal 9 al 13 novembre 2016 presso il: PADIGLIONE 21 - STAND B24. Olivetti Flange\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Olivetti Flange\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-25T20:58:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-15T15:01:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"937\" \/>\n\t<meta property=\"og:image:height\" content=\"912\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adv-admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"adv-admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/\"},\"author\":{\"name\":\"adv-admin\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/person\\\/499f3750bea5d866fa70d06eb6774445\"},\"headline\":\"Siamo presenti a EIMA International 2016\",\"datePublished\":\"2016-10-25T20:58:05+00:00\",\"dateModified\":\"2016-12-15T15:01:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/\"},\"wordCount\":16,\"publisher\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/EIMA2016.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/\",\"name\":\"Siamo presenti a EIMA International 2016 - Olivetti Flange\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/EIMA2016.jpg\",\"datePublished\":\"2016-10-25T20:58:05+00:00\",\"dateModified\":\"2016-12-15T15:01:59+00:00\",\"description\":\"Siamo presenti a EIMA International 2016 a Bologna dal 9 al 13 novembre 2016 presso il: PADIGLIONE 21 - STAND B24. Olivetti Flange\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/EIMA2016.jpg\",\"contentUrl\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/EIMA2016.jpg\",\"width\":937,\"height\":912},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/siamo-presenti-eima-international-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Siamo presenti a EIMA International 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"name\":\"Olivetti Flange\",\"description\":\"Fabbrica Italiana Flange\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#organization\",\"name\":\"Olivetti Flange\",\"url\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.olivettiflange.com\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/logo.png\",\"width\":545,\"height\":74,\"caption\":\"Olivetti Flange\"},\"image\":{\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.olivettiflange.com\\\/it\\\/#\\\/schema\\\/person\\\/499f3750bea5d866fa70d06eb6774445\",\"name\":\"adv-admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb876b41b8875b6872196fc6878c5719352cbd5785d525dc6d215ebf67d1c8f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb876b41b8875b6872196fc6878c5719352cbd5785d525dc6d215ebf67d1c8f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb876b41b8875b6872196fc6878c5719352cbd5785d525dc6d215ebf67d1c8f2?s=96&d=mm&r=g\",\"caption\":\"adv-admin\"},\"url\":\"https:\\\/\\\/www.olivettiflange.com\\\/it\\\/author\\\/adv-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Siamo presenti a EIMA International 2016 - Olivetti Flange","description":"Siamo presenti a EIMA International 2016 a Bologna dal 9 al 13 novembre 2016 presso il: PADIGLIONE 21 - STAND B24. Olivetti Flange","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/","og_locale":"it_IT","og_type":"article","og_title":"Siamo presenti a EIMA International 2016 - Olivetti Flange","og_description":"Siamo presenti a EIMA International 2016 a Bologna dal 9 al 13 novembre 2016 presso il: PADIGLIONE 21 - STAND B24. Olivetti Flange","og_url":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/","og_site_name":"Olivetti Flange","article_published_time":"2016-10-25T20:58:05+00:00","article_modified_time":"2016-12-15T15:01:59+00:00","og_image":[{"width":937,"height":912,"url":"http:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016.jpg","type":"image\/jpeg"}],"author":"adv-admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"adv-admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/#article","isPartOf":{"@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/"},"author":{"name":"adv-admin","@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/person\/499f3750bea5d866fa70d06eb6774445"},"headline":"Siamo presenti a EIMA International 2016","datePublished":"2016-10-25T20:58:05+00:00","dateModified":"2016-12-15T15:01:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/"},"wordCount":16,"publisher":{"@id":"http:\/\/www.olivettiflange.com\/it\/#organization"},"image":{"@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/","url":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/","name":"Siamo presenti a EIMA International 2016 - Olivetti Flange","isPartOf":{"@id":"http:\/\/www.olivettiflange.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/#primaryimage"},"image":{"@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016.jpg","datePublished":"2016-10-25T20:58:05+00:00","dateModified":"2016-12-15T15:01:59+00:00","description":"Siamo presenti a EIMA International 2016 a Bologna dal 9 al 13 novembre 2016 presso il: PADIGLIONE 21 - STAND B24. Olivetti Flange","breadcrumb":{"@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/#primaryimage","url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016.jpg","contentUrl":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2016\/10\/EIMA2016.jpg","width":937,"height":912},{"@type":"BreadcrumbList","@id":"https:\/\/www.olivettiflange.com\/it\/siamo-presenti-eima-international-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.olivettiflange.com\/it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.olivettiflange.com\/it\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Siamo presenti a EIMA International 2016"}]},{"@type":"WebSite","@id":"http:\/\/www.olivettiflange.com\/it\/#website","url":"http:\/\/www.olivettiflange.com\/it\/","name":"Olivetti Flange","description":"Fabbrica Italiana Flange","publisher":{"@id":"http:\/\/www.olivettiflange.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.olivettiflange.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.olivettiflange.com\/it\/#organization","name":"Olivetti Flange","url":"http:\/\/www.olivettiflange.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","contentUrl":"https:\/\/www.olivettiflange.com\/wp-content\/uploads\/2013\/10\/logo.png","width":545,"height":74,"caption":"Olivetti Flange"},"image":{"@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/www.olivettiflange.com\/it\/#\/schema\/person\/499f3750bea5d866fa70d06eb6774445","name":"adv-admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cb876b41b8875b6872196fc6878c5719352cbd5785d525dc6d215ebf67d1c8f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb876b41b8875b6872196fc6878c5719352cbd5785d525dc6d215ebf67d1c8f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb876b41b8875b6872196fc6878c5719352cbd5785d525dc6d215ebf67d1c8f2?s=96&d=mm&r=g","caption":"adv-admin"},"url":"https:\/\/www.olivettiflange.com\/it\/author\/adv-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/posts\/2658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/comments?post=2658"}],"version-history":[{"count":1,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/posts\/2658\/revisions"}],"predecessor-version":[{"id":2660,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/posts\/2658\/revisions\/2660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/media\/2659"}],"wp:attachment":[{"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/media?parent=2658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/categories?post=2658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.olivettiflange.com\/it\/wp-json\/wp\/v2\/tags?post=2658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}